{"id":2982,"date":"2020-10-17T12:56:40","date_gmt":"2020-10-17T10:56:40","guid":{"rendered":"https:\/\/bavarian-bondage.tivendo.com\/produkt\/import-placeholder-for-501\/"},"modified":"2025-12-29T00:10:02","modified_gmt":"2025-12-28T23:10:02","slug":"leinenhanfseil-blau-6mm-exklusiv-einzelseil-4m","status":"publish","type":"product","link":"https:\/\/bavarian-bondage.de\/de\/produkt\/leinenhanfseil-blau-6mm-exklusiv-einzelseil-4m\/","title":{"rendered":"Leinenhanf-Seil Blau 6mm Exklusiv; Einzelseil 4m"},"content":{"rendered":"<h3 style=\"text-align: center\">Leinenhanf-Seil 6mm blau EXKLUSIV<\/h3>\n<p style=\"text-align: center\">Set erweitern, Seile austauschen oder um die Qualit\u00e4t zu pr\u00fcfen.<\/p>\n<p style=\"text-align: center\">Das Leinenhanf-Seil 6mm EXKLUSIV ist sehr weich und geschmeidig! Es wurde mehrmals behandelt, um die beste Qualit\u00e4t zu erhalten. Das Seil besticht durch eine runde, gleichm\u00e4\u00dfige und knotenlose Struktur auf ganzer L\u00e4nge. Des Weiteren werden die Enden mit kleinen Knoten versehen. Da die Seile im Ganzen gef\u00e4rbt wurden, sind diese nicht ganz durchgef\u00e4rbt. Was den Knoten einen besonderen Charakter verleiht.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Details:<\/strong><\/p>\n<p>Leinenhanf-Seil 6mm blau EXKLUSIV<br \/>\n3-sch\u00e4ftig gedreht<br \/>\nFarbe: Blau<br \/>\nTriskenknoten<br \/>\nL\u00e4nge: 1x4m<br \/>\n(Die Seill\u00e4nge kann bis zu 3% von der L\u00e4ngenangabe abweichen)<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong>Hinweis:<\/strong><\/span><\/p>\n<p>Seile regelm\u00e4\u00dfig auf Verschlei\u00df und Besch\u00e4digungen kontrollieren! Bei geschlagenen bzw. gedrehten Seilen kann es passieren, dass diese sich bei der Verwendung lockern!<br \/>\nDie Seile wurden im Ganzen gef\u00e4rbt und sind nicht bis zur Mitte in gleicher Farbe.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lieferumfang:<\/strong> 1x4m Leinenhanf-Seil 6mm blau EXKLUSIV<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<blockquote>\n<p style=\"text-align: center\"><span style=\"color: #333399\">Die Angaben zu den Produkten erfolgt nach bestem Wissen und Gewissen. Alle Ma\u00dfe sind ca-Angaben. Die Benutzung der hier im Shop angebotenen Produkte ist auf eigene Gefahr. Jeder Mensch reagiert anders auf \u00e4u\u00dfere Einwirkungen, auf Lust oder Schmerz usw. Daher kann diesbez\u00fcglich f\u00fcr unsachgem\u00e4\u00dfe Anwendung keine Haftung \u00fcbernommen werden. \u00a0Jeder Benutzer tr\u00e4gt die volle Verantwortung f\u00fcr die Verwendung bzw den richtigen Gebrauch der Produkte und dessen unvorhersehbaren Folgen.<\/span><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Grundpreis: 3,13 \u20ac\/m<\/p>\n<p>Lieferzeit: 5-7 Tage*<\/p>\n","protected":false},"featured_media":9267,"template":"","meta":[],"product_brand":[],"product_cat":[216,217,262,263],"product_tag":[281,282,283,302,528],"class_list":{"0":"post-2982","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bondageseile","7":"product_cat-leinenhanfseil","8":"product_cat-leinenhanfseil-farbig","9":"product_cat-blue-edition","10":"product_tag-hanfseil-6mm","11":"product_tag-hanfseil-blau","12":"product_tag-rope","13":"product_tag-blau","14":"product_tag-leinenhanfseil","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product\/2982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":4,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product\/2982\/revisions"}],"predecessor-version":[{"id":13658,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product\/2982\/revisions\/13658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/media\/9267"}],"wp:attachment":[{"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/media?parent=2982"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product_brand?post=2982"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product_cat?post=2982"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product_tag?post=2982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}