{"id":3063,"date":"2020-10-17T12:57:12","date_gmt":"2020-10-17T10:57:12","guid":{"rendered":"https:\/\/bavarian-bondage.tivendo.com\/produkt\/import-placeholder-for-749\/"},"modified":"2026-05-08T22:14:54","modified_gmt":"2026-05-08T20:14:54","slug":"leinenhanfseil-rot-6mm-exklusiv-set-7x8m-und-2x4m","status":"publish","type":"product","link":"https:\/\/bavarian-bondage.de\/de\/produkt\/leinenhanfseil-rot-6mm-exklusiv-set-7x8m-und-2x4m\/","title":{"rendered":"Leinenhanf-Seil Rot 6mm Exklusiv; Set 7x8m und 2x4m"},"content":{"rendered":"<h3 style=\"text-align: center\">Leinenhanf-Seil\u00a06mm Rot EXKLUSIV<\/h3>\n<p style=\"text-align: center\">Die mitunter beliebteste Bondage-Seilfarbe, das klassische Rot.<\/p>\n<p style=\"text-align: center\">Das Seilset mit 7x8m kann man schon als Klassiker bezeichnen. Erg\u00e4nzt wird das Ganze mit zwei kurzen Seilen, die vielf\u00e4ltige M\u00f6glichkeiten bieten. Das Leinenhanf-Seil 6mm EXKLUSIV ist sehr weich und geschmeidig! Es wurde mehrmals behandelt, um die beste Qualit\u00e4t zu erhalten. Das Seil besticht durch eine runde, gleichm\u00e4\u00dfige und knotenlose Struktur auf ganzer L\u00e4nge. Des Weiteren werden die Enden mit kleinen Knoten versehen.<\/p>\n<p><strong>Details:<\/strong><\/p>\n<p>Leinenhanf-Seil 6mm rot EXKLUSIV<br \/>\n3-sch\u00e4ftig gedreht<br \/>\nFarbe: Rot<br \/>\nTriskenknoten<br \/>\nL\u00e4nge: 7x8m \/ 2x4m<br \/>\n(Die Seill\u00e4nge kann bis zu 3% von der L\u00e4ngenangabe abweichen.)<\/p>\n<p><strong><span style=\"color: #ff0000\">Hinweis:<\/span><\/strong><\/p>\n<p>Seile regelm\u00e4\u00dfig auf Verschlei\u00df und Besch\u00e4digungen kontrollieren! Bei geschlagenen bzw. gedrehten Seilen kann es passieren, dass diese sich bei der Verwendung lockern!<br \/>\nDie Seile wurden im Ganzen gef\u00e4rbt und sind nicht bis zur Mitte in gleicher Farbe.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lieferumfang:<\/strong> Seilset 7x8m und 2x4m Leinenhanf-Seil 6mm rot EXKLUSIV<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<blockquote>\n<p style=\"text-align: center\"><span style=\"color: #333399\">Die Angaben zu den Produkten erfolgt nach bestem Wissen und Gewissen. Alle Ma\u00dfe sind ca-Angaben. Die Benutzung der hier im Shop angebotenen Produkte ist auf eigene Gefahr. Jeder Mensch reagiert anders auf \u00e4u\u00dfere Einwirkungen, auf Lust oder Schmerz usw. Daher kann diesbez\u00fcglich f\u00fcr unsachgem\u00e4\u00dfe Anwendung keine Haftung \u00fcbernommen werden. \u00a0Jeder Benutzer tr\u00e4gt die volle Verantwortung f\u00fcr die Verwendung bzw den richtigen Gebrauch der Produkte und dessen unvorhersehbaren Folgen.<\/span><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Grundpreis: 2,48 \u20ac\/m<\/p>\n<p>Lieferzeit: 5-7 Tage*<\/p>\n","protected":false},"featured_media":10271,"template":"","meta":[],"product_brand":[],"product_cat":[262,277,216,217],"product_tag":[261,292,339,528,221],"class_list":{"0":"post-3063","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-leinenhanfseil-farbig","7":"product_cat-red-edition","8":"product_cat-bondageseile","9":"product_cat-leinenhanfseil","10":"product_tag-bondageseil","11":"product_tag-hanfseil-rot","12":"product_tag-hanfseil-6mm-rot","13":"product_tag-leinenhanfseil","14":"product_tag-seilset","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product\/3063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":5,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product\/3063\/revisions"}],"predecessor-version":[{"id":16442,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product\/3063\/revisions\/16442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/media\/10271"}],"wp:attachment":[{"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/media?parent=3063"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product_brand?post=3063"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product_cat?post=3063"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/de\/wp-json\/wp\/v2\/product_tag?post=3063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}