{"id":2988,"date":"2020-10-17T12:56:40","date_gmt":"2020-10-17T10:56:40","guid":{"rendered":"https:\/\/bavarian-bondage.tivendo.com\/produkt\/import-placeholder-for-515\/"},"modified":"2026-05-11T11:34:35","modified_gmt":"2026-05-11T09:34:35","slug":"cuerda-canamo-lino-rojo-6mm-cuerda-simple-exclusiva-4m","status":"publish","type":"product","link":"https:\/\/bavarian-bondage.de\/es\/produkt\/leinenhanfseil-rot-6mm-exklusiv-einzelseil-4m\/","title":{"rendered":"Cuerda de lino y c\u00e1\u00f1amo roja de 6 mm exclusiva; Cuerda simple 4m"},"content":{"rendered":"<h3 style=\"text-align: center\">Cuerda c\u00e1\u00f1amo lino 6mm rojo EXCLUSIVO<\/h3>\n<p style=\"text-align: center\">Uno de los colores m\u00e1s populares para las cuerdas bondage es el cl\u00e1sico rojo.<\/p>\n<p style=\"text-align: center\">\u00a1La cuerda de lino y c\u00e1\u00f1amo de 6 mm EXCLUSIVA es muy suave y flexible! Ha sido tratado varias veces para mantener la mejor calidad. La cuerda impresiona por su estructura redonda, uniforme y sin nudos en toda su longitud. Adem\u00e1s, los extremos est\u00e1n decorados con peque\u00f1os nudos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Detalles:<\/strong><\/p>\n<p>Cuerda c\u00e1\u00f1amo lino 6mm rojo EXCLUSIVO<br \/>\n3 ejes girados<br \/>\nColor: Rojo<br \/>\nnudo de riesgo<br \/>\nLongitud: 1x4m<br \/>\n(La longitud del cable puede diferir de la longitud especificada hasta en 3%)<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong>Un aviso:<\/strong><\/span><\/p>\n<p>\u00a1Compruebe peri\u00f3dicamente si los cables est\u00e1n desgastados o da\u00f1ados! \u00a1Si las cuerdas se golpean o retuercen, pueden soltarse durante el uso!<br \/>\nLas cuerdas han sido te\u00f1idas en su totalidad y no son del mismo color hasta la mitad.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Alcance de la entrega:<\/strong> Cuerda c\u00e1\u00f1amo lino 1x4m 6mm rojo EXCLUSIVO<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<blockquote>\n<p style=\"text-align: center\"><span style=\"color: #333399\">La informaci\u00f3n sobre los productos se proporciona seg\u00fan nuestro leal saber y entender. Todas las dimensiones son aproximadas. El uso de los productos ofrecidos aqu\u00ed en la tienda es bajo su propia responsabilidad. Cada persona reacciona de manera diferente a las influencias externas, al placer o al dolor, etc. Por lo tanto, no se acepta ninguna responsabilidad por un uso inadecuado.  Cada usuario asume la total responsabilidad por el uso o correcto uso de los productos y sus consecuencias imprevisibles.<\/span><\/p>\n<\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Precio b\u00e1sico: 3,13\u20ac\/m<\/p>\n<p>Plazo de entrega: 5-7 d\u00edas*<\/p>","protected":false},"featured_media":10270,"template":"","meta":[],"product_brand":[],"product_cat":[216,217,262,277],"product_tag":[528,221,261,304],"class_list":{"0":"post-2988","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bondageseile","7":"product_cat-leinenhanfseil","8":"product_cat-leinenhanfseil-farbig","9":"product_cat-red-edition","10":"product_tag-leinenhanfseil","11":"product_tag-seilset","12":"product_tag-bondageseil","13":"product_tag-hanfseil-6mm-exklusiv-rot","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product\/2988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":5,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product\/2988\/revisions"}],"predecessor-version":[{"id":13724,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product\/2988\/revisions\/13724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/media\/10270"}],"wp:attachment":[{"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/media?parent=2988"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product_brand?post=2988"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product_cat?post=2988"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product_tag?post=2988"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}