{"id":3047,"date":"2020-10-17T12:57:04","date_gmt":"2020-10-17T10:57:04","guid":{"rendered":"https:\/\/bavarian-bondage.tivendo.com\/produkt\/import-placeholder-for-710\/"},"modified":"2026-04-22T01:46:07","modified_gmt":"2026-04-21T23:46:07","slug":"cuerda-canamo-lino-rojo-oscuro-5mm-set-exclusivo-7x8m-y-2x4m","status":"publish","type":"product","link":"https:\/\/bavarian-bondage.de\/es\/produkt\/leinenhanfseil-dunkelrot-5mm-exklusiv-set-7x8m-und-2x4m\/","title":{"rendered":"Cuerda de c\u00e1\u00f1amo de lino rojo oscuro 5 mm exclusiva; Conjunto 7x8m y 2x4m"},"content":{"rendered":"<h3 style=\"text-align: center\">Cuerda de lino y c\u00e1\u00f1amo 5mm rojo oscuro EXCLUSIVO<\/h3>\n<p style=\"text-align: center\">El juego de cuerdas de 7x8 m puede describirse como un cl\u00e1sico. Todo se completa con dos cuerdas cortas que ofrecen m\u00faltiples posibilidades. \u00a1La cuerda de lino y c\u00e1\u00f1amo de 5 mm EXCLUSIVA es muy suave y flexible! Ha sido tratado varias veces para mantener la mejor calidad. La cuerda impresiona por su estructura redonda, uniforme y sin nudos en toda su longitud, as\u00ed como por su bonito y llamativo color. Adem\u00e1s, los extremos est\u00e1n provistos de peque\u00f1os nudos; las finas cuerdas de 5 mm son ideales para el bondage art\u00edstico, por supuesto tambi\u00e9n en combinaci\u00f3n con otros colores.<\/p>\n<p><strong>Detalles:<\/strong><\/p>\n<p>Cuerda de lino y c\u00e1\u00f1amo 5mm rojo oscuro EXCLUSIVO<br \/>\n3 ejes girados<br \/>\nColor: rojo oscuro<br \/>\nnudo de riesgo<br \/>\nLongitud: 7x8m \/ 2x4m<br \/>\n(La longitud del cable puede diferir de la longitud especificada hasta en 3%)<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong>Un aviso:<\/strong><\/span><\/p>\n<p>\u00a1Compruebe peri\u00f3dicamente si los cables est\u00e1n desgastados o da\u00f1ados! \u00a1Si las cuerdas se golpean o retuercen, pueden soltarse durante el uso!<br \/>\nLas cuerdas han sido te\u00f1idas en su totalidad y no son del mismo color hasta la mitad.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Alcance de la entrega:<\/strong> Juego de cuerdas 7x8m y 2x4m cuerda c\u00e1\u00f1amo lino 5mm rojo oscuro EXCLUSIVO<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<blockquote>\n<p style=\"text-align: center\"><span style=\"color: #333399\">La informaci\u00f3n sobre los productos se proporciona seg\u00fan nuestro leal saber y entender. Todas las dimensiones son aproximadas. El uso de los productos ofrecidos aqu\u00ed en la tienda es bajo su propia responsabilidad. Cada persona reacciona de manera diferente a las influencias externas, al placer o al dolor, etc. Por lo tanto, no se acepta ninguna responsabilidad por un uso inadecuado.  Cada usuario asume la total responsabilidad por el uso o correcto uso de los productos y sus consecuencias imprevisibles.<\/span><\/p>\n<\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Precio b\u00e1sico: 2,33\u20ac\/m<\/p>\n<p>Plazo de entrega: 5-7 d\u00edas*<\/p>","protected":false},"featured_media":9743,"template":"","meta":[],"product_brand":[],"product_cat":[216,217,262,269],"product_tag":[221,261,270,528],"class_list":{"0":"post-3047","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bondageseile","7":"product_cat-leinenhanfseil","8":"product_cat-leinenhanfseil-farbig","9":"product_cat-dark-red-edition","10":"product_tag-seilset","11":"product_tag-bondageseil","12":"product_tag-hanfseil-dunkelrot-5mm","13":"product_tag-leinenhanfseil","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product\/3047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":5,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product\/3047\/revisions"}],"predecessor-version":[{"id":13671,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product\/3047\/revisions\/13671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/media\/9743"}],"wp:attachment":[{"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/media?parent=3047"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product_brand?post=3047"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product_cat?post=3047"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/es\/wp-json\/wp\/v2\/product_tag?post=3047"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}