{"id":15954,"date":"2025-11-17T11:02:58","date_gmt":"2025-11-17T10:02:58","guid":{"rendered":"https:\/\/bavarian-bondage.de\/?post_type=product&#038;p=15954"},"modified":"2026-04-22T01:46:07","modified_gmt":"2026-04-21T23:46:07","slug":"corda-di-iuta-standard-5mm-set-esclusivo-3x8m","status":"publish","type":"product","link":"https:\/\/bavarian-bondage.de\/it\/produkt\/juteseil-standard-5mm-exklusiv-set-3x8m\/","title":{"rendered":"Corda di iuta standard 5mm Esclusiva; Set 3x8m"},"content":{"rendered":"<h3 style=\"text-align: center\">La corda di iuta da 5 mm ESCLUSIVA<\/h3>\n<p style=\"text-align: center\">Ideale per iniziare come rigger o per espandere un set esistente.<\/p>\n<p style=\"text-align: center\">La corda di iuta \u00e8 strettamente attorcigliata e inizialmente un po&#039; rigida e ruvida, ma con l&#039;uso migliora! Inoltre la corda era dotata di piccoli nodi terminali. La raffinazione conferisce alla corda di iuta un bellissimo aspetto color caramello. La corda \u00e8 composta da un unico filato ed \u00e8 quindi uniforme e solitamente senza nodi su tutta la sua lunghezza.<\/p>\n<p><strong>\u00a0Dettagli:<\/strong><\/p>\n<p>Corda di iuta 5mm ESCLUSIVA<br \/>\n3 alberi strettamente attorcigliati<br \/>\nColori caramello<br \/>\nNodi terminali piccoli<br \/>\nLunghezza: 3x8 m<br \/>\n(La lunghezza della fune pu\u00f2 variare fino a 3% rispetto alla lunghezza specificata.)<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong>Un avviso:<\/strong><\/span><\/p>\n<p>Controllare regolarmente che le corde non siano usurate o danneggiate!<br \/>\nSe le corde vengono battute o attorcigliate, potrebbero allentarsi durante l&#039;uso!<br \/>\nNon lavare le corde di iuta. \u00c8 meglio pulire con un panno umido.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fornitura:<\/strong> Corda di iuta 3x8m 5mm ESCLUSIVA<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<blockquote>\n<p style=\"text-align: center\"><span style=\"color: #333399\">Le informazioni sui prodotti sono fornite al meglio delle nostre conoscenze e convinzioni. Tutte le dimensioni sono approssimative. L&#039;uso dei prodotti offerti qui nel negozio \u00e8 a tuo rischio e pericolo. Ogni persona reagisce in modo diverso agli influssi esterni, al piacere o al dolore, ecc. Pertanto non si assume alcuna responsabilit\u00e0 per un uso improprio.  Ogni utente \u00e8 pienamente responsabile dell&#039;uso o del corretto utilizzo dei prodotti e delle sue imprevedibili conseguenze.<\/span><\/p>\n<\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Prezzo base: 2,21 \u20ac\/mt<\/p>\n<p>Tempi di consegna: 5-7 giorni*<\/p>","protected":false},"featured_media":15996,"template":"","meta":[],"product_brand":[],"product_cat":[216,222,294,560],"product_tag":[221,273,297,329],"class_list":{"0":"post-15954","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bondageseile","7":"product_cat-alle-produkte","8":"product_cat-juteseile","9":"product_cat-jute-standard-5mm","10":"product_tag-seilset","11":"product_tag-5mm","12":"product_tag-juteseil","13":"product_tag-bondageseile","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/15954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/15954\/revisions"}],"predecessor-version":[{"id":15993,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/15954\/revisions\/15993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/media\/15996"}],"wp:attachment":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/media?parent=15954"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_brand?post=15954"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_cat?post=15954"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_tag?post=15954"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}