{"id":17677,"date":"2026-07-21T13:33:46","date_gmt":"2026-07-21T11:33:46","guid":{"rendered":"https:\/\/bavarian-bondage.de\/?post_type=product&#038;p=17677"},"modified":"2026-07-22T13:01:58","modified_gmt":"2026-07-22T11:01:58","slug":"corda-di-lino-e-canapa-multicolore-verde-verde-chiaro-5-mm","status":"publish","type":"product","link":"https:\/\/bavarian-bondage.de\/it\/produkt\/leinenhanf-seil-mehrfarbig-gruen-hellgruen-5mm\/","title":{"rendered":"Corda di lino e canapa, multicolore, verde-verde chiaro, 5 mm"},"content":{"rendered":"<h3 style=\"text-align: center\">Corda di lino e canapa 5 mm Verde - verde chiaro ESCLUSIVA<\/h3>\n<p style=\"text-align: center\">La corda di canapa e lino 5mm EXCLUSIVE \u00e8 molto morbida ed elastica! \u00c8 stato trattato pi\u00f9 volte per mantenere la migliore qualit\u00e0. La corda colpisce per la sua struttura rotonda, uniforme e senza nodi su tutta la sua lunghezza. Inoltre le estremit\u00e0 sono decorate con piccoli nodini. Poich\u00e9 le corde sono state tinte nel loro insieme, non sono completamente colorate.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dettagli:<\/strong><\/p>\n<p>Corda di lino e canapa 5 mm multicolore verde-verde chiaro ESCLUSIVA<br \/>\n3 alberi torniti<br \/>\nColore: verde - verde chiaro<br \/>\nNodo traballante<br \/>\nLunghezza: 1x8 m<br \/>\n(La lunghezza della fune pu\u00f2 discostarsi dalla lunghezza specificata fino a 3%)<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong>Un avviso:<\/strong><\/span><\/p>\n<p>Controlla regolarmente le corde per verificare l&#039;usura e i danni! Con le corde attorcigliate o intrecciate, pu\u00f2 succedere che si allentino durante l&#039;uso! Le corde sono state tinte in massa e non fino all&#039;anima.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fornitura:<\/strong> 1 corda di lino e canapa da 8 m, 5 mm, verde - Verde chiaro ESCLUSIVA<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<blockquote>\n<p style=\"text-align: center\"><span style=\"color: #333399\">Le informazioni sui prodotti sono fornite al meglio delle nostre conoscenze e convinzioni. Tutte le dimensioni sono approssimative. L&#039;uso dei prodotti offerti qui nel negozio \u00e8 a tuo rischio e pericolo. Ogni persona reagisce in modo diverso agli influssi esterni, al piacere o al dolore, ecc. Pertanto non si assume alcuna responsabilit\u00e0 per un uso improprio.  Ogni utente \u00e8 pienamente responsabile dell&#039;uso o del corretto utilizzo dei prodotti e delle sue imprevedibili conseguenze.<\/span><\/p>\n<\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Tempi di consegna: 5-7 giorni*<\/p>","protected":false},"featured_media":17763,"template":"","meta":[],"product_brand":[],"product_cat":[216,217,262],"product_tag":[529,260,261],"class_list":["post-17677","product","type-product","status-publish","has-post-thumbnail","product_cat-bondageseile","product_cat-leinenhanfseil","product_cat-leinenhanfseil-farbig","product_tag-leinenhanf","product_tag-hanfseil","product_tag-bondageseil","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-product-safety-information"],"_links":{"self":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/17677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":4,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/17677\/revisions"}],"predecessor-version":[{"id":17835,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/17677\/revisions\/17835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/media\/17763"}],"wp:attachment":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/media?parent=17677"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_brand?post=17677"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_cat?post=17677"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_tag?post=17677"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}