{"id":2964,"date":"2020-10-17T12:58:31","date_gmt":"2020-10-17T10:58:31","guid":{"rendered":"https:\/\/bavarian-bondage.tivendo.com\/produkt\/import-placeholder-for-455\/"},"modified":"2025-11-09T15:52:47","modified_gmt":"2025-11-09T14:52:47","slug":"corda-singola-esclusiva-in-iuta-di-alta-qualita-da-5-mm-da-8-m","status":"publish","type":"product","link":"https:\/\/bavarian-bondage.de\/it\/produkt\/high-class-jute-5mm-exklusiv-einzelseil-8m\/","title":{"rendered":"Juta di alta qualit\u00e0 5mm ESCLUSIVO; Corda singola 8m"},"content":{"rendered":"<h3 style=\"text-align: center\">Juta di alta qualit\u00e0 5mm ESCLUSIVO<\/h3>\n<p style=\"text-align: center\">Sostituisci una corda, amplia il set o semplicemente controlla la qualit\u00e0.<\/p>\n<p style=\"text-align: center\">Anche durante la produzione delle corde viene prestata attenzione alla migliore qualit\u00e0, il che \u00e8 molto vantaggioso per un utilizzo successivo. Le corde vengono lavorate e rifinite a mano fino a ottenere una delicata finitura bianca.<\/p>\n<p style=\"text-align: center\">Le estremit\u00e0 sono legate con piccoli nodi trisque, il che rende la legatura molto pi\u00f9 semplice.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dettagli:<\/strong><br \/>\nJuta di alta qualit\u00e0 5mm ESCLUSIVO<br \/>\n3 alberi torniti<br \/>\nTono caramellato leggero<br \/>\nNodi terminali piccoli<br \/>\nLunghezza: 1x8 m<br \/>\n(La lunghezza della fune pu\u00f2 variare fino a 3% rispetto alla lunghezza specificata.)<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong>Un avviso:<\/strong><\/span><\/p>\n<p>Controllare regolarmente che le corde non siano usurate o danneggiate!<br \/>\nSe le corde vengono battute o attorcigliate, potrebbero allentarsi durante l&#039;uso!<br \/>\nNon lavare le corde di iuta. \u00c8 meglio pulire con un panno umido.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fornitura:<\/strong> 1x8m Iuta di alta classe 5mm ESCLUSIVO<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: center\"><span style=\"color: #333399\">Le informazioni sui prodotti sono fornite al meglio delle nostre conoscenze e convinzioni. Tutte le dimensioni sono approssimative. L&#039;uso dei prodotti offerti qui nel negozio \u00e8 a tuo rischio e pericolo. Ogni persona reagisce in modo diverso agli influssi esterni, al piacere o al dolore, ecc. Pertanto non si assume alcuna responsabilit\u00e0 per un uso improprio.  Ogni utente \u00e8 pienamente responsabile dell&#039;uso o del corretto utilizzo dei prodotti e delle sue imprevedibili conseguenze<\/span>.<\/p>\n<\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Prezzo base: 2,98 \u20ac\/mt<\/p>\n<p>Tempi di consegna: 5-7 giorni*<\/p>","protected":false},"featured_media":8368,"template":"","meta":[],"product_brand":[],"product_cat":[216,294,295],"product_tag":[298,261,296,297],"class_list":{"0":"post-2964","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bondageseile","7":"product_cat-juteseile","8":"product_cat-high-class-jute-5mm","9":"product_tag-seil-set","10":"product_tag-bondageseil","11":"product_tag-high-class-jute","12":"product_tag-juteseil","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/2964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":5,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/2964\/revisions"}],"predecessor-version":[{"id":13828,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product\/2964\/revisions\/13828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/media\/8368"}],"wp:attachment":[{"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/media?parent=2964"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_brand?post=2964"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_cat?post=2964"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bavarian-bondage.de\/it\/wp-json\/wp\/v2\/product_tag?post=2964"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}